{"id":3050,"date":"2011-09-24T10:27:48","date_gmt":"2011-09-24T10:27:48","guid":{"rendered":"http:\/\/www.parnes.com\/wordpress\/index.php\/2011\/09\/24\/peter_on_phone_god_morgon_10\/"},"modified":"2011-09-24T10:27:48","modified_gmt":"2011-09-24T10:27:48","slug":"peter_on_phone_god_morgon_10","status":"publish","type":"post","link":"https:\/\/www.parnes.com\/blog\/index.php\/2011\/09\/24\/peter_on_phone_god_morgon_10\/","title":{"rendered":"Peter on Phone: God morgon."},"content":{"rendered":"<div class=\"pp_items\">\n<div class=\"pp_item\" align=\"center\"><img decoding=\"async\" src=\"http:\/\/static.pixelpipe.com\/bb996130-2aaa-4863-beeb-af1294032111_b.jpg\" style=\"max-width: 100%;\" \/><\/p>\n<p>Ser ni nysn\u00f6n d\u00e4r uppe?<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ser ni nysn\u00f6n d\u00e4r uppe?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[975],"class_list":["post-3050","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-httpwww-parnes-comwordpressp1021"],"_links":{"self":[{"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3050"}],"version-history":[{"count":0,"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3050\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parnes.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}